{"id":152,"date":"2023-06-16T17:18:47","date_gmt":"2023-06-16T17:18:47","guid":{"rendered":"https:\/\/justmute.ai\/?p=152"},"modified":"2023-06-16T17:19:18","modified_gmt":"2023-06-16T17:19:18","slug":"on-device-meeting-transcription-and-speech-recognition-testing","status":"publish","type":"post","link":"https:\/\/justmute.ai\/fr\/on-device-meeting-transcription-and-speech-recognition-testing\/","title":{"rendered":"Transcription de r\u00e9union sur appareil et tests de reconnaissance vocale"},"content":{"rendered":"<p>La communication vocale est l\u2019une des fonctionnalit\u00e9s les plus fr\u00e9quemment n\u00e9glig\u00e9es qui peuvent faire ou d\u00e9faire une application. Il existe de nombreux probl\u00e8mes graves tels que la distorsion du son, l&#039;\u00e9cho, le bruit de fond et les interf\u00e9rences provenant d&#039;autres sources qui ont un impact sur notre fa\u00e7on de travailler au quotidien.<\/p>\n\n\n\n<p>En fait, les personnes qui travaillent dans des environnements bruyants sont souvent confront\u00e9es \u00e0 des d\u00e9fis uniques li\u00e9s \u00e0 leur communication orale. Lors de la conception de nouvelles applications, il est important de conserver tous ces \u00e9l\u00e9ments dans votre plan de d\u00e9veloppement.<\/p>\n\n\n\n<p>Cet article pr\u00e9sentera les probl\u00e8mes de communication vocale courants rencontr\u00e9s par les \u00e9quipes et comment les att\u00e9nuer gr\u00e2ce aux nouveaux SDK cr\u00e9\u00e9s par Mute.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La voix compte partout<\/h2>\n\n\n\n<p>Avant la pand\u00e9mie et jusqu\u2019\u00e0 aujourd\u2019hui, l\u2019utilisation des communications vocales a explos\u00e9 sur une multitude d\u2019appareils, de plates-formes et d\u2019applications.<\/p>\n\n\n\n<p>Alors que notre monde a \u00e9t\u00e9 physiquement s\u00e9par\u00e9 au cours des deux derni\u00e8res ann\u00e9es, notre besoin de nous sentir connect\u00e9s les uns aux autres a augment\u00e9 de fa\u00e7on exponentielle. Aujourd\u2019hui, nous disposons d\u2019encore plus d\u2019applications de communication d\u2019\u00e9quipe. Et de plus en plus d\u2019options que nous utilisons int\u00e8grent obligatoirement la voix et la vid\u00e9o, garantissant ainsi la qualit\u00e9 de nos appels.<\/p>\n\n\n\n<p>La communication vocale est fondamentale pour se sentir connect\u00e9, tout comme la vid\u00e9o. C\u2019est pourquoi les applications de communication d\u2019\u00e9quipe comme Zoom, Microsoft Teams et autres ont explos\u00e9 pendant la pand\u00e9mie. Ils ont permis aux gens de se connecter, de se voir et de s&#039;entendre facilement malgr\u00e9 la distance.<\/p>\n\n\n\n<p>En tant qu\u2019humains, nous avons besoin d\u2019entendre la voix des autres pour nous sentir connect\u00e9s. Notre d\u00e9sir d\u2019entendre les autres parler ne s\u2019arr\u00eate pas aux appels bidirectionnels. L&#039;application uniquement audio, Clubhouse, permet aux utilisateurs d&#039;\u00e9couter des discussions audio dans diff\u00e9rentes salles virtuelles. C&#039;est pourquoi il a \u00e9t\u00e9 d\u00e9crit comme \u00ab un mashup consistant \u00e0 \u00e9couter un podcast tout en faisant d\u00e9filer votre fil Twitter et en assistant \u00e0 une conf\u00e9rence \u00e0 distance \u00bb.<\/p>\n\n\n\n<p>Alors naturellement, nous avons besoin et comptons sur les voix et les sons pour communiquer, que ce soit nous qui entamons une discussion ou non.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Communication vocale au-del\u00e0 des conversations claires<\/h2>\n\n\n\n<p>La communication vocale pr\u00e9sente de nombreux avantages, notamment\u00a0:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>R\u00e9duire les probl\u00e8mes de communication entre les consommateurs et les entreprises<\/li>\n\n\n\n<li>Fournir un filtre antibruit dans les environnements bruyants<\/li>\n\n\n\n<li>Emp\u00eacher les allers-retours des collaborateurs pour acc\u00e9l\u00e9rer le travail<\/li>\n\n\n\n<li>Vous aider \u00e0 impressionner vos clients et \u00e0 pr\u00e9venir les plaintes li\u00e9es au bruit<\/li>\n\n\n\n<li>Am\u00e9liorer la qualit\u00e9 de notre voix et \u00e9liminer les malentendus.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">La voix fournit du contexte et de la clart\u00e9<\/h2>\n\n\n\n<p>Pensez \u00e0 quel point il peut \u00eatre difficile de s&#039;assurer que votre communication textuelle uniquement a le bon contexte. Dois-je ajouter un emoji ou un point d&#039;exclamation ? Nous pouvons facilement faire la diff\u00e9rence entre la sinc\u00e9rit\u00e9 et l\u2019humour lors d\u2019un appel, alors que le faire par SMS ou par chat peut \u00eatre probl\u00e9matique. Dans un environnement professionnel, le contexte peut faire la diff\u00e9rence en termes d\u2019assistance, de service et de ventes.<\/p>\n\n\n\n<p>Mais garantir des conversations claires n\u2019est pas le seul avantage \u00e0 garder \u00e0 l\u2019esprit pour votre logiciel.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La voix permet de meilleures exp\u00e9riences client<\/h2>\n\n\n\n<p>Les conversations vocales sont cruciales pour les entreprises grand public, car elles contribuent \u00e0 r\u00e9duire le temps de transaction et \u00e0 offrir une exp\u00e9rience plus simple aux clients. Les parties peuvent rapidement \u00e9tablir une connexion personnelle pour effectuer rapidement de petites t\u00e2ches via un appel vocal, comme indiquer au livreur comment trouver la porte d\u00e9rob\u00e9e ou confirmer vos donn\u00e9es m\u00e9dicales aupr\u00e8s d&#039;un professionnel de la sant\u00e9.<\/p>\n\n\n\n<p>De brefs appels vocaux en cas d&#039;urgence peuvent nous aider \u00e0 avancer plus rapidement et \u00e0 \u00eatre plus productifs et efficaces dans nos t\u00e2ches quotidiennes. De nombreuses entreprises proposent le chat en direct et m\u00eame les appels en face \u00e0 face comme point de contact principal. Ceux-ci sont utiles \u00e0 la fois pour g\u00e9rer des questions faciles \u00e0 r\u00e9pondre et des cas d\u2019utilisation.<\/p>\n\n\n\n<p>Ces discussions textuelles sont g\u00e9n\u00e9ralement le premier choix de chacun pour une r\u00e9solution rapide, qu&#039;elles soient accessibles via un site Web ou un support sur les r\u00e9seaux sociaux. Mais la possibilit\u00e9 de passer \u00e0 un bref appel est inestimable et peut aider \u00e0 \u00e9viter l\u2019\u00e9change de centaines de messages et la frustration croissante des deux c\u00f4t\u00e9s.<\/p>\n\n\n\n<p>Une fois qu&#039;un client peut facilement opter pour un appel audio avec un repr\u00e9sentant de l&#039;assistance pour lui demander comment faire fonctionner son nouveau gadget en temps r\u00e9el, la facilit\u00e9 de communication vaut son pesant d&#039;or du point de vue de l&#039;exp\u00e9rience client.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Toutes les applications doivent offrir une bonne qualit\u00e9 vocale<\/h2>\n\n\n\n<p>Pensez \u00e0 la derni\u00e8re fois que vous avez re\u00e7u un appel, mais que la connexion \u00e9tait tellement mauvaise et que vous avez vraiment besoin de r\u00e9parer quelque chose rapidement. Ou lorsque des \u00e9chos ou des bruits de fond forts vous emp\u00eachent d\u2019entendre une question ou une explication importante.<\/p>\n\n\n\n<p>Ces probl\u00e8mes audio peuvent rendre les appels vocaux inutilisables et frustrants pour toutes les personnes impliqu\u00e9es. Mais ajouter de la voix aux applications et aux plates-formes n\u2019est pas aussi simple que simplement int\u00e9grer WebRTC. Garantir une exp\u00e9rience vocale de haute qualit\u00e9 n\u00e9cessite une bonne conception audio et l\u2019int\u00e9gration de syst\u00e8mes de traitement vocal de premier plan. Ce dernier devrait \u00eatre capable d&#039;\u00e9liminer le bruit de fond, de supprimer l&#039;\u00e9cho de la pi\u00e8ce et <a href=\"#!\" data-type=\"internal\" data-id=\"#!\">r\u00e9soudre les probl\u00e8mes d&#039;\u00e9cho acoustique<\/a> pour que la voix r\u00e9sultante soit limpide.<\/p>\n\n\n\n<p>L\u2019ensemble de ce processus doit \u00eatre effectu\u00e9 en temps r\u00e9el sans imposer de charge \u00e0 l\u2019application ou \u00e0 l\u2019appareil. Sinon, toute l\u2019exp\u00e9rience utilisateur au sein de n\u2019importe quelle application serait ruin\u00e9e.<\/p>","protected":false},"excerpt":{"rendered":"<p>La communication vocale est l&#039;une des fonctionnalit\u00e9s les plus souvent n\u00e9glig\u00e9es, et elle peut \u00eatre d\u00e9terminante pour le succ\u00e8s ou l&#039;\u00e9chec d&#039;une application. De nombreux probl\u00e8mes graves, tels que la distorsion sonore, l&#039;\u00e9cho, le bruit de fond et les interf\u00e9rences provenant d&#039;autres sources, impactent notre fa\u00e7on de travailler au quotidien. En effet, les personnes travaillant dans des environnements bruyants sont souvent confront\u00e9es \u00e0 des d\u00e9fis sp\u00e9cifiques li\u00e9s [\u2026]<\/p>","protected":false},"author":1,"featured_media":153,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tips-and-best-practices","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/justmute.ai\/fr\/wp-json\/wp\/v2\/posts\/152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/justmute.ai\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justmute.ai\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justmute.ai\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/justmute.ai\/fr\/wp-json\/wp\/v2\/comments?post=152"}],"version-history":[{"count":0,"href":"https:\/\/justmute.ai\/fr\/wp-json\/wp\/v2\/posts\/152\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justmute.ai\/fr\/wp-json\/wp\/v2\/media\/153"}],"wp:attachment":[{"href":"https:\/\/justmute.ai\/fr\/wp-json\/wp\/v2\/media?parent=152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justmute.ai\/fr\/wp-json\/wp\/v2\/categories?post=152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justmute.ai\/fr\/wp-json\/wp\/v2\/tags?post=152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}