{"id":125,"date":"2023-06-16T16:37:48","date_gmt":"2023-06-16T16:37:48","guid":{"rendered":"https:\/\/justmute.ai\/?p=125"},"modified":"2023-06-16T16:44:12","modified_gmt":"2023-06-16T16:44:12","slug":"state-of-remote-work-in-2023-7-big-trends-to-follow","status":"publish","type":"post","link":"https:\/\/justmute.ai\/es\/state-of-remote-work-in-2023-7-big-trends-to-follow\/","title":{"rendered":"Estado del trabajo remoto en 2023 (7 grandes tendencias a seguir)"},"content":{"rendered":"<p>La comunicaci\u00f3n por voz es una de las funciones que con m\u00e1s frecuencia se pasan por alto y que pueden hacer que una aplicaci\u00f3n sea exitosa o desventajosa. Hay muchos problemas graves, como la distorsi\u00f3n del sonido, el eco, el ruido de fondo y la interferencia de otras fuentes, que afectan la forma en que trabajamos todos los d\u00edas.<\/p>\n\n\n\n<p>De hecho, las personas que trabajan en ambientes ruidosos a menudo enfrentan desaf\u00edos \u00fanicos relacionados con su comunicaci\u00f3n hablada. Al dise\u00f1ar nuevas aplicaciones, es importante tenerlas todas en su plan de desarrollo.<\/p>\n\n\n\n<p>Este art\u00edculo presentar\u00e1 problemas comunes de comunicaci\u00f3n de voz que encuentran los equipos y c\u00f3mo mitigarlos a trav\u00e9s de los nuevos SDK creados por Mute.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La voz importa en todas partes<\/h2>\n\n\n\n<p>Antes de la pandemia y hasta hoy, el uso de las comunicaciones de voz se dispar\u00f3 en una gran cantidad de dispositivos, plataformas y aplicaciones.<\/p>\n\n\n\n<p>Como nuestro mundo ha estado f\u00edsicamente separado durante los \u00faltimos dos a\u00f1os, nuestra necesidad de sentirnos conectados unos con otros ha crecido exponencialmente. Hoy en d\u00eda, tenemos a\u00fan m\u00e1s aplicaciones de comunicaci\u00f3n en equipo. Y cada vez son m\u00e1s las opciones que utilizamos incorporan voz y v\u00eddeo de forma imprescindible, asegurando la calidad de nuestras llamadas.<\/p>\n\n\n\n<p>La comunicaci\u00f3n por voz es fundamental para sentirse conectado, al igual que el v\u00eddeo. Es por eso que las aplicaciones de comunicaci\u00f3n en equipo como Zoom, Microsoft Teams y otras explotaron durante la pandemia. Facilitaron que las personas se conectaran, vieran y escucharan a pesar de la distancia.<\/p>\n\n\n\n<p>Como seres humanos, necesitamos escuchar las voces de otras personas para sentirnos conectados. Nuestro deseo de escuchar a los dem\u00e1s hablar no se limita a las llamadas bidireccionales. La aplicaci\u00f3n de solo audio, Clubhouse, permite a los usuarios escuchar charlas de audio en diferentes salas virtuales. Es por eso que se lo describe como &quot;una combinaci\u00f3n de escuchar un podcast mientras navegas por tu cuenta de Twitter y asistes a una conferencia de forma remota&quot;.<\/p>\n\n\n\n<p>Entonces, naturalmente, necesitamos y confiamos en voces y sonidos para comunicarnos, ya sea que seamos nosotros los que iniciamos una discusi\u00f3n o no.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Comunicaci\u00f3n por voz m\u00e1s all\u00e1 de conversaciones claras<\/h2>\n\n\n\n<p>La comunicaci\u00f3n por voz tiene muchos beneficios, que incluyen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Reducir la falta de comunicaci\u00f3n entre consumidores y empresas<\/li>\n\n\n\n<li>Proporcionar un filtro de cancelaci\u00f3n de ruido en entornos ruidosos.<\/li>\n\n\n\n<li>Evitar los movimientos de los empleados para acelerar el trabajo<\/li>\n\n\n\n<li>Ayud\u00e1ndole a impresionar a los clientes y prevenir quejas por ruido<\/li>\n\n\n\n<li>Mejorando la calidad de nuestra voz y eliminando malentendidos.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">La voz proporciona contexto y claridad.<\/h2>\n\n\n\n<p>Piense en lo laborioso que puede ser intentar asegurarse de que su comunicaci\u00f3n de s\u00f3lo texto tenga el contexto adecuado. \u00bfDebo agregar un emoji o un signo de exclamaci\u00f3n? Podemos diferenciar f\u00e1cilmente entre sinceridad y humor en una llamada, mientras que hacerlo a trav\u00e9s de mensajes de texto o chat puede resultar problem\u00e1tico. En un entorno empresarial, el contexto puede marcar la diferencia en soporte, servicio y ventas.<\/p>\n\n\n\n<p>Pero garantizar conversaciones claras no es el \u00fanico beneficio que debe tener en cuenta para su software.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La voz permite mejores experiencias para los clientes<\/h2>\n\n\n\n<p>Las conversaciones de voz son cruciales para las empresas de consumo porque ayudan a reducir el tiempo de transacci\u00f3n y brindan una experiencia m\u00e1s sencilla a los clientes. Las partes pueden establecer r\u00e1pidamente una conexi\u00f3n personal para realizar peque\u00f1as tareas r\u00e1pidamente a trav\u00e9s de una llamada de voz, desde decirle al repartidor c\u00f3mo encontrar la puerta trasera o confirmar sus datos m\u00e9dicos con un profesional de la salud.<\/p>\n\n\n\n<p>Las llamadas de voz breves en momentos de emergencia pueden ayudarnos a avanzar m\u00e1s r\u00e1pido y ser m\u00e1s productivos y eficientes en nuestras tareas diarias. Muchas empresas ofrecen chat en vivo e incluso llamadas cara a cara como punto de contacto principal. Son \u00fatiles tanto para manejar preguntas f\u00e1ciles de responder como para casos de uso.<\/p>\n\n\n\n<p>Estos chats de texto suelen ser la primera opci\u00f3n de todos para una resoluci\u00f3n r\u00e1pida, ya sea que se pueda acceder a ellos a trav\u00e9s de un sitio web o de las redes sociales. Pero la capacidad de escalar a una llamada breve es invaluable y puede ayudar a evitar el intercambio de cientos de mensajes y una creciente frustraci\u00f3n en ambas partes.<\/p>\n\n\n\n<p>Una vez que un cliente puede optar f\u00e1cilmente por una llamada de audio con un representante de soporte para preguntarle c\u00f3mo hacer que su nuevo dispositivo funcione en tiempo real, la facilidad de comunicaci\u00f3n vale su peso en oro desde la perspectiva de la experiencia del cliente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Todas las aplicaciones deben ofrecer buena calidad de voz.<\/h2>\n\n\n\n<p>Piense en la \u00faltima vez que estuvo en una llamada pero la conexi\u00f3n era tan mala y realmente necesita arreglar algo r\u00e1pidamente. O cuando los ecos o los ruidos de fondo fuertes le impidieron escuchar una pregunta o explicaci\u00f3n importante.<\/p>\n\n\n\n<p>Estos problemas de audio pueden hacer que las llamadas de voz sean inutilizables y frustrantes para todos los involucrados. Pero agregar voz a aplicaciones y plataformas no es tan f\u00e1cil como simplemente integrar WebRTC. Garantizar una experiencia de voz de alta calidad requiere un buen dise\u00f1o de audio y la integraci\u00f3n de sistemas de procesamiento de voz de primer nivel. Este \u00faltimo deber\u00eda poder eliminar el ruido de fondo, eliminar el eco ambiental y <a href=\"#!\" data-type=\"internal\" data-id=\"#!\">solucionar problemas de eco ac\u00fastico<\/a> para que la voz resultante sea cristalina.<\/p>\n\n\n\n<p>Todo este proceso debe realizarse en tiempo real sin imponer una carga a la aplicaci\u00f3n o dispositivo. De lo contrario, se arruinar\u00eda toda la experiencia del usuario dentro de cualquier aplicaci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>La comunicaci\u00f3n por voz es una de las caracter\u00edsticas que m\u00e1s se pasan por alto y que puede ser clave para el \u00e9xito o el fracaso de una aplicaci\u00f3n. Existen muchos problemas graves, como la distorsi\u00f3n del sonido, el eco, el ruido de fondo y las interferencias de otras fuentes, que afectan nuestra forma de trabajar a diario. De hecho, quienes trabajan en entornos ruidosos a menudo se enfrentan a desaf\u00edos \u00fanicos relacionados con [\u2026]<\/p>","protected":false},"author":1,"featured_media":126,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-company","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/justmute.ai\/es\/wp-json\/wp\/v2\/posts\/125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/justmute.ai\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/justmute.ai\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/justmute.ai\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/justmute.ai\/es\/wp-json\/wp\/v2\/comments?post=125"}],"version-history":[{"count":0,"href":"https:\/\/justmute.ai\/es\/wp-json\/wp\/v2\/posts\/125\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/justmute.ai\/es\/wp-json\/wp\/v2\/media\/126"}],"wp:attachment":[{"href":"https:\/\/justmute.ai\/es\/wp-json\/wp\/v2\/media?parent=125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/justmute.ai\/es\/wp-json\/wp\/v2\/categories?post=125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/justmute.ai\/es\/wp-json\/wp\/v2\/tags?post=125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}